{"id":8785,"date":"2025-01-09T14:26:44","date_gmt":"2025-01-09T19:26:44","guid":{"rendered":"https:\/\/procana.org\/site\/?p=8785"},"modified":"2025-02-07T17:03:12","modified_gmt":"2025-02-07T22:03:12","slug":"obras-de-corazon","status":"publish","type":"post","link":"https:\/\/procana.org\/site\/obras-de-corazon\/","title":{"rendered":"Obras de Coraz\u00f3n"},"content":{"rendered":"\n<p><strong>M\u00e1s de 30.000 familias de los diferentes municipios se han beneficiado de forma directa con los diferentes programas de la Fundaci\u00f3n Coraz\u00f3n de Ca\u00f1a, durante el a\u00f1o 2024.&nbsp;<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"574\" src=\"https:\/\/procana.org\/site\/wp-content\/uploads\/2024\/12\/LOGO_FUNDACION_CDC-1024x574.png\" alt=\"\" class=\"wp-image-8786\" style=\"width:221px;height:auto\"\/><\/figure>\n\n\n\n<p>La Fundaci\u00f3n Coraz\u00f3n de Ca\u00f1a sigue apostando por un futuro m\u00e1s sostenible en el valle geogr\u00e1fico del r\u00edo Cauca.<\/p>\n\n\n\n<p>En el a\u00f1o 2024, la Fundaci\u00f3n Coraz\u00f3n de Ca\u00f1a realiz\u00f3 una inversi\u00f3n significativa que super\u00f3 los $6.300 millones de pesos, gracias a los valiosos aportes de los cultivadores de ca\u00f1a de az\u00facar y de los ingenios azucareros. A esta cifra se sumaron recursos adicionales por un valor de&nbsp; $3.100 millones de pesos, provenientes del gobierno regional, de diversas fundaciones y de empresas privadas. En conjunto, estas iniciativas permitieron destinar un total de $9.400 millones de pesos al fortalecimiento de la infraestructura educativa y comunitaria de esta zona.<\/p>\n\n\n\n<p>Esta inversi\u00f3n tuvo como objetivo primordial cerrar las brechas en el aprendizaje, especialmente en la lectura y escritura, de los ni\u00f1os y ni\u00f1as que asisten a escuelas p\u00fablicas en el nivel de educaci\u00f3n b\u00e1sica primaria. Adem\u00e1s, se busc\u00f3 mejorar la trayectoria educativa de j\u00f3venes de entre 14 y 25 a\u00f1os, facilitando su acceso a becas de formaci\u00f3n vocacional, ofreciendo orientaci\u00f3n socio-ocupacional; y apoyo en el proceso para el desarrollo de sus proyectos de vida. La Fundaci\u00f3n Coraz\u00f3n de Ca\u00f1a est\u00e1 comprometida, a contribuir de manera sustancial al bienestar y la educaci\u00f3n de las futuras generaciones.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mejora de infraestructura <\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"8787\" src=\"https:\/\/procana.org\/site\/wp-content\/uploads\/2024\/12\/BPMZ3821-768x1024.jpg\" alt=\"\" class=\"wp-image-8787\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"8789\" src=\"https:\/\/procana.org\/site\/wp-content\/uploads\/2024\/12\/DJI_0056-1024x576.jpg\" alt=\"\" class=\"wp-image-8789\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"8791\" src=\"https:\/\/procana.org\/site\/wp-content\/uploads\/2024\/12\/WhatsApp-Image-2024-10-21-at-1.03.32-PM-1-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-8791\"\/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Infraestructura Educativa<\/h3>\n\n\n\n<p>En alianza con la Gobernaci\u00f3n del Valle del Cauca se optimizaron las condiciones de infraestructura en cocinas y comedores para 21 sedes educativas p\u00fablicas. Esta iniciativa permitir\u00e1 que m\u00e1s de 7.000 estudiantes disfruten de alimentos preparados en sitio, mejorando de esta forma su nutrici\u00f3n y factores asociados al aprendizaje y la permanencia escolar.&nbsp;<\/p>\n\n\n\n<p>La inversi\u00f3n en infraestructura educativa se focaliz\u00f3 principalmente en escuelas p\u00fablicas de las zonas rurales del Valle del Cauca, sur de Risaralda y Caldas.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"8794\" src=\"https:\/\/procana.org\/site\/wp-content\/uploads\/2024\/12\/DMF3367-1024x576.jpg\" alt=\"\" class=\"wp-image-8794\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"8795\" src=\"https:\/\/procana.org\/site\/wp-content\/uploads\/2024\/12\/IMG_0527-1-1024x768.jpg\" alt=\"\" class=\"wp-image-8795\"\/><\/figure>\n<\/figure>\n\n\n\n<p>Trabajamos en equipo con la Secretar\u00eda de Educaci\u00f3n municipal y regional, docentes, directivos, y las familias; para fortalecer los aprendizajes y habilidades socio emocionales de los ni\u00f1os y ni\u00f1as menores de 10 a\u00f1os.&nbsp;<\/p>\n\n\n\n<p>El reto es aumentar la capacidad de aprendizaje, hoy el 55% de los ni\u00f1os y ni\u00f1as que llegan a la edad de 10 a\u00f1os, no han logrado desarrollar la capacidad para comprender textos sencillos. Si no atendemos entre todos esta situaci\u00f3n, seguiremos observando bajos indicadores de calidad y eficiencia educativa, afectando la competitividad del valle geogr\u00e1fico del r\u00edo Cauca. Solo el 30% de los estudiantes que se grad\u00faan del sistema educativo acceden a una educaci\u00f3n superior; el 17% de los adolescentes, desertan en la transici\u00f3n a la educaci\u00f3n media y el 27% de los j\u00f3venes entre los 18 y 24 a\u00f1os, conocidos como ninis, ni estudian, ni generan ingresos a trav\u00e9s de un empleo o emprendimiento. (Ministerio de educaci\u00f3n nacional 2023 &#8211; Raddar 2023)<\/p>\n\n\n\n<p>La Fundaci\u00f3n Coraz\u00f3n de Ca\u00f1a cualific\u00f3 a m\u00e1s de 180 docentes y directivos docentes a trav\u00e9s de la estrategia \u201cAprendamos todos a leer\u201d del Banco Interamericano de Desarrollo, donde comparti\u00f3&nbsp; las buenas pr\u00e1cticas para mejorar el aprendizaje b\u00e1sico y el desarrollo de habilidades socioemocionales. Iniciativas desarrolladas y aplicadas por algunos colegios del sector, y a su misma vez, son usadas por facultades en educaci\u00f3n de las universidades de la regi\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"8798\" src=\"https:\/\/procana.org\/site\/wp-content\/uploads\/2024\/12\/Copia-de-DSC06759-1024x683.jpg\" alt=\"\" class=\"wp-image-8798\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"8797\" src=\"https:\/\/procana.org\/site\/wp-content\/uploads\/2024\/12\/Copia-de-DSC07015-1024x683.jpg\" alt=\"\" class=\"wp-image-8797\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"8796\" src=\"https:\/\/procana.org\/site\/wp-content\/uploads\/2024\/12\/WhatsApp-Image-2024-10-23-at-9.26.27-AM-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-8796\"\/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 30.000 familias de los diferentes municipios se han beneficiado de forma directa con los diferentes programas de la Fundaci\u00f3n Coraz\u00f3n de Ca\u00f1a, durante el a\u00f1o 2024.&nbsp; La Fundaci\u00f3n Coraz\u00f3n de Ca\u00f1a sigue apostando por un futuro m\u00e1s sostenible en el valle geogr\u00e1fico del r\u00edo Cauca. En el a\u00f1o 2024, la Fundaci\u00f3n Coraz\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":442,"featured_media":8799,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[9,10,1],"tags":[],"class_list":["post-8785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","category-revista-principal","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/procana.org\/site\/wp-json\/wp\/v2\/posts\/8785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/procana.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/procana.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/procana.org\/site\/wp-json\/wp\/v2\/users\/442"}],"replies":[{"embeddable":true,"href":"https:\/\/procana.org\/site\/wp-json\/wp\/v2\/comments?post=8785"}],"version-history":[{"count":2,"href":"https:\/\/procana.org\/site\/wp-json\/wp\/v2\/posts\/8785\/revisions"}],"predecessor-version":[{"id":8900,"href":"https:\/\/procana.org\/site\/wp-json\/wp\/v2\/posts\/8785\/revisions\/8900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/procana.org\/site\/wp-json\/wp\/v2\/media\/8799"}],"wp:attachment":[{"href":"https:\/\/procana.org\/site\/wp-json\/wp\/v2\/media?parent=8785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/procana.org\/site\/wp-json\/wp\/v2\/categories?post=8785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/procana.org\/site\/wp-json\/wp\/v2\/tags?post=8785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}